{"id":97,"date":"2025-06-02T21:42:11","date_gmt":"2025-06-02T21:42:11","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=97"},"modified":"2025-06-02T21:42:11","modified_gmt":"2025-06-02T21:42:11","slug":"dra-saene-spinelli-uma-medica-para-chamar-de-sua","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/","title":{"rendered":"Dra.Saene Spinelli &#8211;\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d"},"content":{"rendered":"\n<p>Em um consult\u00f3rio acolhedor em S\u00e3o Paulo ou em atendimentos online com pacientes de todo o Brasil, hist\u00f3rias de supera\u00e7\u00e3o silenciosa ganham voz e dire\u00e7\u00e3o. Quem conduz esse processo de transforma\u00e7\u00e3o \u00e9 a Dra. Saene Spinelli, m\u00e9dica que tem se tornado refer\u00eancia nacional quando o assunto \u00e9 emagrecimento ap\u00f3s os 40 anos. Com uma abordagem que vai muito al\u00e9m de balan\u00e7as e calorias: ela cuida de emo\u00e7\u00f5es, hist\u00f3rias e recome\u00e7os.<\/p>\n\n\n\n<p>Formada em Medicina e p\u00f3s-graduada em Nutrologia e Endocrinologia, Dra. Saene tamb\u00e9m se especializou em Medicina do Estilo de Vida, Neuroci\u00eancia Comportamental, Sa\u00fade da Mulher e pr\u00e1ticas integrativas. Por\u00e9m, seu maior diferencial n\u00e3o est\u00e1 apenas nos t\u00edtulos, e sim na forma como cuida: com escuta acolhedora, acompanhamento semanal e um plano terap\u00eautico realmente individualizado. Sempre movida por um prop\u00f3sito: transformar vidas.<\/p>\n\n\n\n<p>Enquanto a maioria dos m\u00e9dicos v\u00ea o paciente a cada dois ou tr\u00eas meses, Dra. Saene acompanha de forma di\u00e1ria e personalizada, ajustando semanalmente sono, intestino, alimenta\u00e7\u00e3o, estresse, suplementos e autoestima. \u00c9 um cuidado de verdade, adaptado \u00e0 rotina, aos sentimentos e \u00e0s necessidades de cada um. Com foco em um emagrecimento sustent\u00e1vel e com base em evid\u00eancias cient\u00edficas.<\/p>\n\n\n\n<p>\u201cEmagrecer, para mim, \u00e9 sobre devolver amor-pr\u00f3prio, romper ciclos de culpa e resgatar a identidade. N\u00e3o \u00e9 s\u00f3 sobre o que comem, mas sobre o que sentem\u201d, afirma.<\/p>\n\n\n\n<p>Sua trajet\u00f3ria tamb\u00e9m \u00e9 inspiradora. Come\u00e7ou como recepcionista no Hospital Benefic\u00eancia Portuguesa de Santo Andr\u00e9, onde hoje atua como Diretora de Qualidade. Foram oito promo\u00e7\u00f5es, muito esfor\u00e7o e uma virada de vida: cursar Medicina j\u00e1 adulta, conciliando um curso integral com o trabalho noturno.<\/p>\n\n\n\n<p>Hoje, Dra. Saene \u00e9 idealizadora do m\u00e9todo MUDAR.me, onde compartilha conte\u00fados sobre sa\u00fade emocional, emagrecimento sustent\u00e1vel e transforma\u00e7\u00e3o verdadeira, sempre com base em ci\u00eancia e conex\u00e3o real.<\/p>\n\n\n\n<p>\u201cMinha maior conquista \u00e9 ouvir de uma paciente: \u2018Voc\u00ea n\u00e3o s\u00f3 me ajudou a emagrecer. Voc\u00ea me devolveu a vontade de viver\u2019. \u00c9 isso que a move.\u201d<\/p>\n\n\n\n<p>Com planos de lan\u00e7ar seu infoproduto digital ainda este ano, ela quer ampliar o alcance da sua miss\u00e3o: mostrar \u00e0s mulheres 40+ que \u00e9 poss\u00edvel emagrecer com sa\u00fade, dignidade, acolhimento.<\/p>\n\n\n\n<p>\ud83d\udcf2 Quer conhecer mais de perto esse acompanhamento \u00fanico?\nSiga a Dra. Saene no Instagram: @<a href=\"http:\/\/instagram.com\/dra.saenespinelli\">dra.saenespinelli<\/a>\nE no YouTube\u00a0<a href=\"https:\/\/www.youtube.com\/@drasaenespinelli\">https:\/\/www.youtube.com\/@drasaenespinelli<\/a><\/p>\n\n\n<!-- wp:image \"id\":29271,\"sizeSlug\":\"large\",\"linkDestination\":\"none\" -->\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.michelasi.com.br\/wp-content\/uploads\/2025\/06\/05896e81-9423-46bd-8c08-4207ffbbe82e-682x1024.jpeg\" alt=\"\" class=\"wp-image-29271\"\/><\/figure>\n<!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>Em um consult\u00f3rio acolhedor em S\u00e3o Paulo ou em atendimentos online com pacientes de todo o Brasil, hist\u00f3rias de supera\u00e7\u00e3o silenciosa ganham voz e dire\u00e7\u00e3o. Quem conduz esse processo de transforma\u00e7\u00e3o \u00e9 a Dra. Saene Spinelli, m\u00e9dica que tem se tornado refer\u00eancia nacional quando o assunto \u00e9 emagrecimento ap\u00f3s os 40 anos. Com uma abordagem \u2026<\/p>\n","protected":false},"author":2,"featured_media":96,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-97","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"Em um consult\u00f3rio acolhedor em S\u00e3o Paulo ou em atendimentos online com pacientes de todo o Brasil, hist\u00f3rias de supera\u00e7\u00e3o silenciosa ganham voz e dire\u00e7\u00e3o. Quem conduz esse processo de transforma\u00e7\u00e3o \u00e9 a Dra. Saene Spinelli, m\u00e9dica que tem se tornado refer\u00eancia nacional quando o assunto \u00e9 emagrecimento ap\u00f3s os 40 anos. Com uma abordagem \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-02T21:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"Dra.Saene Spinelli &#8211;\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d\",\"datePublished\":\"2025-06-02T21:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg\",\"articleSection\":[\"Famosos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\",\"name\":\"Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg\",\"datePublished\":\"2025-06-02T21:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg\",\"width\":1320,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dra.Saene Spinelli &#8211;\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/","og_locale":"pt_BR","og_type":"article","og_title":"Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado","og_description":"Em um consult\u00f3rio acolhedor em S\u00e3o Paulo ou em atendimentos online com pacientes de todo o Brasil, hist\u00f3rias de supera\u00e7\u00e3o silenciosa ganham voz e dire\u00e7\u00e3o. Quem conduz esse processo de transforma\u00e7\u00e3o \u00e9 a Dra. Saene Spinelli, m\u00e9dica que tem se tornado refer\u00eancia nacional quando o assunto \u00e9 emagrecimento ap\u00f3s os 40 anos. Com uma abordagem \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/","og_site_name":"Portal do Estado","article_published_time":"2025-06-02T21:42:11+00:00","og_image":[{"width":1320,"height":799,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","type":"image\/jpeg"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"Dra.Saene Spinelli &#8211;\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d","datePublished":"2025-06-02T21:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/"},"wordCount":420,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","articleSection":["Famosos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/","name":"Dra.Saene Spinelli -\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","datePublished":"2025-06-02T21:42:11+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","width":1320,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/02\/dra-saene-spinelli-uma-medica-para-chamar-de-sua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"Dra.Saene Spinelli &#8211;\u00a0\u201cUma m\u00e9dica para chamar de sua.\u201d"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/IMG_6260.jpeg","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"predecessor-version":[{"id":98,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/97\/revisions\/98"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/96"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}