{"id":9145,"date":"2026-05-11T01:11:51","date_gmt":"2026-05-11T01:11:51","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=9145"},"modified":"2026-05-11T01:11:51","modified_gmt":"2026-05-11T01:11:51","slug":"grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/","title":{"rendered":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es"},"content":{"rendered":"\n<p>Neste Dia das M\u00e3es, o Grupo MW preparou uma homenagem especial dedicada a todas as mulheres que representam amor, for\u00e7a, dedica\u00e7\u00e3o e inspira\u00e7\u00e3o dentro das fam\u00edlias brasileiras.<\/p>\n\n\n\n<p>Em nome dos jornalistas <strong>Thiago Michelasi<\/strong> e <strong>Wilker Manoel Soares<\/strong>, a mensagem refor\u00e7a o reconhecimento e a gratid\u00e3o por todas as m\u00e3es que, diariamente, desempenham um papel fundamental na constru\u00e7\u00e3o de hist\u00f3rias, valores e sonhos.<\/p>\n\n\n\n<p>\u201cHoje \u00e9 um dia de celebrar o amor mais puro e verdadeiro que existe. Queremos desejar um Feliz Dia das M\u00e3es para todas essas mulheres incr\u00edveis que transformam vidas com carinho, coragem e dedica\u00e7\u00e3o\u201d, destacaram os jornalistas em homenagem divulgada pelo Grupo MW.<\/p>\n\n\n\n<p>A data, marcada por emo\u00e7\u00e3o e homenagens em todo o pa\u00eds, tamb\u00e9m serve como momento de reflex\u00e3o sobre a import\u00e2ncia da presen\u00e7a materna na sociedade. Seja atrav\u00e9s do cuidado, da prote\u00e7\u00e3o ou dos ensinamentos di\u00e1rios, as m\u00e3es seguem sendo exemplos de for\u00e7a e supera\u00e7\u00e3o.<\/p>\n\n\n\n<p>O Grupo MW aproveitou a ocasi\u00e3o para agradecer todas as m\u00e3es que acompanham os projetos, programas e a\u00e7\u00f5es desenvolvidas pelo grupo, desejando que o amor e a uni\u00e3o estejam presentes em cada lar nesta data t\u00e3o especial.<\/p>\n\n\n\n<p>\u201cQue nunca faltem motivos para sorrir, receber carinho e sentir o reconhecimento por tudo o que representam. Feliz Dia das M\u00e3es!\u201d, finalizaram Thiago Michelasi e Wilker Manoel Soares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste Dia das M\u00e3es, o Grupo MW preparou uma homenagem especial dedicada a todas as mulheres que representam amor, for\u00e7a, dedica\u00e7\u00e3o e inspira\u00e7\u00e3o dentro das fam\u00edlias brasileiras. Em nome dos jornalistas Thiago Michelasi e Wilker Manoel Soares, a mensagem refor\u00e7a o reconhecimento e a gratid\u00e3o por todas as m\u00e3es que, diariamente, desempenham um papel fundamental \u2026<\/p>\n","protected":false},"author":2,"featured_media":9144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"Neste Dia das M\u00e3es, o Grupo MW preparou uma homenagem especial dedicada a todas as mulheres que representam amor, for\u00e7a, dedica\u00e7\u00e3o e inspira\u00e7\u00e3o dentro das fam\u00edlias brasileiras. Em nome dos jornalistas Thiago Michelasi e Wilker Manoel Soares, a mensagem refor\u00e7a o reconhecimento e a gratid\u00e3o por todas as m\u00e3es que, diariamente, desempenham um papel fundamental \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T01:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es\",\"datePublished\":\"2026-05-11T01:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\",\"name\":\"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png\",\"datePublished\":\"2026-05-11T01:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/","og_locale":"pt_BR","og_type":"article","og_title":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado","og_description":"Neste Dia das M\u00e3es, o Grupo MW preparou uma homenagem especial dedicada a todas as mulheres que representam amor, for\u00e7a, dedica\u00e7\u00e3o e inspira\u00e7\u00e3o dentro das fam\u00edlias brasileiras. Em nome dos jornalistas Thiago Michelasi e Wilker Manoel Soares, a mensagem refor\u00e7a o reconhecimento e a gratid\u00e3o por todas as m\u00e3es que, diariamente, desempenham um papel fundamental \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/","og_site_name":"Portal do Estado","article_published_time":"2026-05-11T01:11:51+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","type":"image\/png"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es","datePublished":"2026-05-11T01:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/"},"wordCount":257,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","articleSection":["Geral"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/","name":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","datePublished":"2026-05-11T01:11:51+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/11\/grupo-mw-presta-homenagem-emocionante-as-maes-neste-dia-das-maes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"Grupo MW presta homenagem emocionante \u00e0s m\u00e3es neste Dia das M\u00e3es"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/C9885E88-535B-4187-8060-3F02CDF584BB.png","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9145"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9145\/revisions"}],"predecessor-version":[{"id":9146,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9145\/revisions\/9146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/9144"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}