{"id":9058,"date":"2026-05-08T22:07:15","date_gmt":"2026-05-08T22:07:15","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=9058"},"modified":"2026-05-08T22:07:15","modified_gmt":"2026-05-08T22:07:15","slug":"pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/","title":{"rendered":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins"},"content":{"rendered":"\n<p>A fam\u00edlia da dupla Henrique e Juliano passou por momentos de tens\u00e3o nesta sexta-feira ap\u00f3s um helic\u00f3ptero ligado aos artistas realizar um pouso de emerg\u00eancia em uma fazenda na zona rural de Porto Nacional.<\/p>\n\n\n\n<p>Segundo a assessoria dos cantores, quem pilotava a aeronave era Edson Reis. Apesar do susto, ele sofreu apenas ferimentos leves e passa bem.<\/p>\n\n\n\n<p>Moradores da regi\u00e3o relataram ter ouvido um forte estrondo pouco antes do pouso for\u00e7ado. Testemunhas afirmaram que o helic\u00f3ptero sobrevoava propriedades da \u00e1rea em baixa altitude, o que chamou aten\u00e7\u00e3o e provocou preocupa\u00e7\u00e3o entre pessoas pr\u00f3ximas.<\/p>\n\n\n\n<p>Ap\u00f3s a repercuss\u00e3o do caso, Henrique e Juliano apareceram nas redes sociais para tranquilizar os f\u00e3s. Os artistas explicaram que houve apenas danos materiais e destacaram a experi\u00eancia do pai como piloto.<\/p>\n\n\n\n<p>Juliano tamb\u00e9m comentou que a aeronave est\u00e1 registrada em seu nome, mas refor\u00e7ou que n\u00e3o estava presente no momento do incidente.<\/p>\n\n\n\n<p>A Pol\u00edcia Militar do Tocantins informou que equipes acompanharam a ocorr\u00eancia e confirmaram que ningu\u00e9m ficou gravemente ferido. As causas do pouso emergencial seguem sendo investigadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fam\u00edlia da dupla Henrique e Juliano passou por momentos de tens\u00e3o nesta sexta-feira ap\u00f3s um helic\u00f3ptero ligado aos artistas realizar um pouso de emerg\u00eancia em uma fazenda na zona rural de Porto Nacional. Segundo a assessoria dos cantores, quem pilotava a aeronave era Edson Reis. Apesar do susto, ele sofreu apenas ferimentos leves e \u2026<\/p>\n","protected":false},"author":2,"featured_media":9057,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"A fam\u00edlia da dupla Henrique e Juliano passou por momentos de tens\u00e3o nesta sexta-feira ap\u00f3s um helic\u00f3ptero ligado aos artistas realizar um pouso de emerg\u00eancia em uma fazenda na zona rural de Porto Nacional. Segundo a assessoria dos cantores, quem pilotava a aeronave era Edson Reis. Apesar do susto, ele sofreu apenas ferimentos leves e \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T22:07:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins\",\"datePublished\":\"2026-05-08T22:07:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\"},\"wordCount\":207,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg\",\"articleSection\":[\"Famosos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\",\"name\":\"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg\",\"datePublished\":\"2026-05-08T22:07:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/","og_locale":"pt_BR","og_type":"article","og_title":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado","og_description":"A fam\u00edlia da dupla Henrique e Juliano passou por momentos de tens\u00e3o nesta sexta-feira ap\u00f3s um helic\u00f3ptero ligado aos artistas realizar um pouso de emerg\u00eancia em uma fazenda na zona rural de Porto Nacional. Segundo a assessoria dos cantores, quem pilotava a aeronave era Edson Reis. Apesar do susto, ele sofreu apenas ferimentos leves e \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/","og_site_name":"Portal do Estado","article_published_time":"2026-05-08T22:07:15+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","type":"image\/jpeg"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins","datePublished":"2026-05-08T22:07:15+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/"},"wordCount":207,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","articleSection":["Famosos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/","name":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","datePublished":"2026-05-08T22:07:15+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/08\/pai-de-henrique-e-juliano-pilota-helicoptero-em-pouso-forcado-no-tocantins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"Pai de Henrique e Juliano pilota helic\u00f3ptero em pouso for\u00e7ado no Tocantins"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Helicoptero-de-Henrique-e-Juliano-faz-pouso-forcado-em-fazenda-no-Tocantins.jpg","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9058"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9058\/revisions"}],"predecessor-version":[{"id":9059,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9058\/revisions\/9059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/9057"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}