{"id":9025,"date":"2026-05-07T18:27:53","date_gmt":"2026-05-07T18:27:53","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=9025"},"modified":"2026-05-07T18:27:53","modified_gmt":"2026-05-07T18:27:53","slug":"briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/","title":{"rendered":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial"},"content":{"rendered":"\n<p>O cantor Ed Motta se envolveu em uma confus\u00e3o em um restaurante da zona sul do Rio de Janeiro que terminou com um cliente ferido e registro policial. O epis\u00f3dio aconteceu ap\u00f3s um desentendimento relacionado \u00e0 cobran\u00e7a de taxa de rolha no estabelecimento.<\/p>\n\n\n\n<p>Segundo relatos prestados \u00e0s autoridades, um homem que estava em uma mesa pr\u00f3xima \u00e0 do artista afirmou ter sofrido um ferimento na cabe\u00e7a durante a briga e precisou levar sete pontos. O caso foi registrado na 15\u00aa Delegacia de Pol\u00edcia da G\u00e1vea como les\u00e3o corporal.<\/p>\n\n\n\n<p>De acordo com a vers\u00e3o apresentada pela v\u00edtima, a situa\u00e7\u00e3o saiu do controle depois que Ed Motta deixou o local. O cliente afirmou que acabou sendo atingido em meio \u00e0 confus\u00e3o envolvendo pessoas que acompanhavam o cantor.<\/p>\n\n\n\n<p>Ainda segundo o depoimento, uma garrafa teria sido arremessada durante o tumulto, provocando o ferimento. Um dos amigos do artista, Diogo Coutinho do Couto, j\u00e1 foi chamado para prestar esclarecimentos \u00e0s autoridades.<\/p>\n\n\n\n<p>A confus\u00e3o teria come\u00e7ado ap\u00f3s o restaurante cobrar uma taxa para permitir o consumo de uma bebida levada pelo pr\u00f3prio m\u00fasico. Irritado com a cobran\u00e7a, Ed Motta deixou o estabelecimento alterado.<\/p>\n\n\n\n<p>Imagens de seguran\u00e7a registraram o momento em que o cantor arremessa uma cadeira dentro do restaurante durante a sa\u00edda. O objeto acabou atingindo de rasp\u00e3o um funcion\u00e1rio do local.<\/p>\n\n\n\n<p>O epis\u00f3dio segue sob investiga\u00e7\u00e3o policial para apura\u00e7\u00e3o das responsabilidades e circunst\u00e2ncias da confus\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cantor Ed Motta se envolveu em uma confus\u00e3o em um restaurante da zona sul do Rio de Janeiro que terminou com um cliente ferido e registro policial. O epis\u00f3dio aconteceu ap\u00f3s um desentendimento relacionado \u00e0 cobran\u00e7a de taxa de rolha no estabelecimento. Segundo relatos prestados \u00e0s autoridades, um homem que estava em uma mesa \u2026<\/p>\n","protected":false},"author":2,"featured_media":9024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"O cantor Ed Motta se envolveu em uma confus\u00e3o em um restaurante da zona sul do Rio de Janeiro que terminou com um cliente ferido e registro policial. O epis\u00f3dio aconteceu ap\u00f3s um desentendimento relacionado \u00e0 cobran\u00e7a de taxa de rolha no estabelecimento. Segundo relatos prestados \u00e0s autoridades, um homem que estava em uma mesa \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T18:27:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial\",\"datePublished\":\"2026-05-07T18:27:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg\",\"articleSection\":[\"Famosos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\",\"name\":\"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg\",\"datePublished\":\"2026-05-07T18:27:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/","og_locale":"pt_BR","og_type":"article","og_title":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado","og_description":"O cantor Ed Motta se envolveu em uma confus\u00e3o em um restaurante da zona sul do Rio de Janeiro que terminou com um cliente ferido e registro policial. O epis\u00f3dio aconteceu ap\u00f3s um desentendimento relacionado \u00e0 cobran\u00e7a de taxa de rolha no estabelecimento. Segundo relatos prestados \u00e0s autoridades, um homem que estava em uma mesa \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/","og_site_name":"Portal do Estado","article_published_time":"2026-05-07T18:27:53+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","type":"image\/jpeg"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial","datePublished":"2026-05-07T18:27:53+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/"},"wordCount":269,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","articleSection":["Famosos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/","name":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","datePublished":"2026-05-07T18:27:53+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/briga-em-restaurante-envolvendo-ed-motta-acaba-com-cliente-ferido-e-investigacao-policial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"Briga em restaurante envolvendo Ed Motta acaba com cliente ferido e investiga\u00e7\u00e3o policial"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/Ed-Motta.jpg","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9025"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9025\/revisions"}],"predecessor-version":[{"id":9026,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9025\/revisions\/9026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/9024"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}