{"id":9001,"date":"2026-05-07T17:33:16","date_gmt":"2026-05-07T17:33:16","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=9001"},"modified":"2026-05-07T17:33:16","modified_gmt":"2026-05-07T17:33:16","slug":"filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/","title":{"rendered":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos"},"content":{"rendered":"\n<p>A pequena Mavie viralizou nas redes sociais ap\u00f3s protagonizar um momento divertido e cheio de espontaneidade durante uma partida do Santos FC. A filha de Neymar reagiu imediatamente ap\u00f3s o craque sofrer uma falta mais dura em campo e acabou encantando os internautas.<\/p>\n\n\n\n<p>No v\u00eddeo compartilhado nas redes, a menina aparece indignada com o lance e repreende o jogador advers\u00e1rio do San Lorenzo. \u201cN\u00e3o pode, mo\u00e7o!\u201d, disse Mavie, demonstrando preocupa\u00e7\u00e3o com o pai e arrancando risadas dos presentes.<\/p>\n\n\n\n<p>A cena ganhou grande repercuss\u00e3o entre f\u00e3s do jogador, que destacaram a personalidade da crian\u00e7a e a rela\u00e7\u00e3o carinhosa entre pai e filha. Muitos internautas comentaram o jeito protetor da pequena diante da situa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O momento aconteceu poucos dias ap\u00f3s outra pol\u00eamica envolvendo Neymar nos bastidores do clube. Recentemente, o Santos confirmou um desentendimento entre o atacante e Robinho Jr. durante uma atividade interna realizada ap\u00f3s o cl\u00e1ssico contra o Palmeiras.<\/p>\n\n\n\n<p>Segundo relatos divulgados pela imprensa, Neymar teria se incomodado com uma jogada do jovem atleta durante o treino, o que gerou uma discuss\u00e3o entre os dois. Depois do epis\u00f3dio, representantes de Robinho Jr. solicitaram esclarecimentos formais ao clube sobre o ocorrido.<\/p>\n\n\n\n<p>Apesar da repercuss\u00e3o nos bastidores, foi a rea\u00e7\u00e3o espont\u00e2nea de Mavie que acabou dominando as redes sociais e conquistando os f\u00e3s do camisa santista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pequena Mavie viralizou nas redes sociais ap\u00f3s protagonizar um momento divertido e cheio de espontaneidade durante uma partida do Santos FC. A filha de Neymar reagiu imediatamente ap\u00f3s o craque sofrer uma falta mais dura em campo e acabou encantando os internautas. No v\u00eddeo compartilhado nas redes, a menina aparece indignada com o lance \u2026<\/p>\n","protected":false},"author":2,"featured_media":9000,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"A pequena Mavie viralizou nas redes sociais ap\u00f3s protagonizar um momento divertido e cheio de espontaneidade durante uma partida do Santos FC. A filha de Neymar reagiu imediatamente ap\u00f3s o craque sofrer uma falta mais dura em campo e acabou encantando os internautas. No v\u00eddeo compartilhado nas redes, a menina aparece indignada com o lance \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T17:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos\",\"datePublished\":\"2026-05-07T17:33:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\"},\"wordCount\":250,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg\",\"articleSection\":[\"Famosos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\",\"name\":\"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg\",\"datePublished\":\"2026-05-07T17:33:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/","og_locale":"pt_BR","og_type":"article","og_title":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado","og_description":"A pequena Mavie viralizou nas redes sociais ap\u00f3s protagonizar um momento divertido e cheio de espontaneidade durante uma partida do Santos FC. A filha de Neymar reagiu imediatamente ap\u00f3s o craque sofrer uma falta mais dura em campo e acabou encantando os internautas. No v\u00eddeo compartilhado nas redes, a menina aparece indignada com o lance \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/","og_site_name":"Portal do Estado","article_published_time":"2026-05-07T17:33:16+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","type":"image\/jpeg"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos","datePublished":"2026-05-07T17:33:16+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/"},"wordCount":250,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","articleSection":["Famosos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/","name":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","datePublished":"2026-05-07T17:33:16+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2026\/05\/07\/filha-de-neymar-rouba-a-cena-ao-defender-o-pai-durante-partida-do-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"Filha de Neymar rouba a cena ao defender o pai durante partida do Santos"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2026\/05\/pXXp00aI-Design-sem-nome-9.jpg","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9001"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9001\/revisions"}],"predecessor-version":[{"id":9002,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9001\/revisions\/9002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/9000"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}