{"id":212,"date":"2025-06-09T17:08:43","date_gmt":"2025-06-09T17:08:43","guid":{"rendered":"https:\/\/portaldoestado.com.br\/?p=212"},"modified":"2025-06-09T17:08:43","modified_gmt":"2025-06-09T17:08:43","slug":"nefroclinicas-abre-nova-unidade-no-shopping-da-gavea","status":"publish","type":"post","link":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/","title":{"rendered":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea"},"content":{"rendered":"\n<p>O secret\u00e1rio de sa\u00fade do Rio de Janeiro Daniel Soranz esteve presente e atestando a qualidade do grupo NefroCl\u00ednicas.<\/p>\n\n\n\n<p><strong>NefroCl\u00ednicas<\/strong> com quase seis anos de exist\u00eancia, com sua funda\u00e7\u00e3o em Belo Horizonte &#8211; MG, inaugurou mais uma unidade no Rio de Janeiro no bairro da G\u00e1vea, nesta quinta-feira (05) no Centro M\u00e9dico do Shopping da G\u00e1vea, em parceria com o Hospital S\u00e3o Lucas Copacabana.<\/p>\n\n\n<!-- wp:image \"id\":42762,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-04-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42762\" \/><\/figure>\n<!-- \/wp:post-content -->\n\n<!-- wp:paragraph -->\n<p>\u201c<em>O objetivo principal dessa parceria \u00e9 expandir o acesso a um cuidado nefrol\u00f3gico de qualidade, unindo a expertise do grupo NefroCl\u00ednicas com a infraestrutura e tradi\u00e7\u00e3o do Hospital S\u00e3o Lucas Copacabana. Juntos, levamos ao Centro M\u00e9dico da G\u00e1vea um atendimento integrado e focado na sa\u00fade renal, oferecendo comodidade, praticidade e cuidado humanizado aos pacientes da regi\u00e3o<\/em>\u201d, explica \u00c1lvaro Steiner, nefrologista do Hospital S\u00e3o Lucas Copacabana e respons\u00e1vel t\u00e9cnico do novo centro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image \"id\":42760,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-02-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42760\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p><strong>Crescimento e expans\u00e3o da NefroCl\u00ednicas:<\/strong>\nAo longo desses quase 6 anos, a NefroCl\u00ednicas cresceu, e hoje, \u00e9 um companhia com presen\u00e7a em diversos estados do Brasil.\nCom unidades em Ipanema-RJ, Barra da Tijuca-RJ, Volta Redonda-RJ, Bras\u00edlia-DF, S\u00e3o Lu\u00eds-MA, Belo Horizonte-MG, Nova Lima &#8211; MG, Curitiba-PR e, recentemente, em \u00c1guas Claras-DF, replicando o modelo de cuidado e atendimento que tornou o grupo NefroCl\u00ednicas uma refer\u00eancia nacional em Sa\u00fade baseada em valor.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image \"id\":42761,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-03-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42761\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Com uma linha de cuidado centrada no paciente, a equipe \u00e9 composta por nefrologistas renomados e comprometidos com a pr\u00e1tica da nefrologia. A empresa vem se destacando na \u00e1rea de di\u00e1lise peritoneal, hemodi\u00e1lise, hemodiafiltra\u00e7\u00e3o, transplante renal e o tratamento conservador, abordagem focada na preven\u00e7\u00e3o e.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No pr\u00f3ximo m\u00eas ser\u00e1 inaugurada a Nefroclinicas Botafogo e no dia 21 de junho realiza um Simp\u00f3sio com m\u00e9dicos internacionais, Hotel Prodigy Santos Dumont, no\u00a0Rio\u00a0de\u00a0Janeiro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image \"id\":42765,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-07-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42765\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:image \"id\":42764,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-06-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42764\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:image \"id\":42763,\"align\":\"center\" -->\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/clickfato.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-05-mavicaassessoria.jpg\" alt=\"\" class=\"wp-image-42763\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p> #claudelopes70 #nefroclinicas #fredpontes<\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio de sa\u00fade do Rio de Janeiro Daniel Soranz esteve presente e atestando a qualidade do grupo NefroCl\u00ednicas. NefroCl\u00ednicas com quase seis anos de exist\u00eancia, com sua funda\u00e7\u00e3o em Belo Horizonte \u2013 MG, inaugurou mais uma unidade no Rio de Janeiro no bairro da G\u00e1vea, nesta quinta-feira (05) no Centro M\u00e9dico do Shopping da \u2026<\/p>\n","protected":false},"author":2,"featured_media":211,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[9,26],"class_list":["post-212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","tag-claudelopes70","tag-nefroclinicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio de sa\u00fade do Rio de Janeiro Daniel Soranz esteve presente e atestando a qualidade do grupo NefroCl\u00ednicas. NefroCl\u00ednicas com quase seis anos de exist\u00eancia, com sua funda\u00e7\u00e3o em Belo Horizonte \u2013 MG, inaugurou mais uma unidade no Rio de Janeiro no bairro da G\u00e1vea, nesta quinta-feira (05) no Centro M\u00e9dico do Shopping da \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal do Estado\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T17:08:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\"},\"headline\":\"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea\",\"datePublished\":\"2025-06-09T17:08:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\"},\"wordCount\":325,\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg\",\"keywords\":[\"claudelopes70\",\"nefroclinicas\"],\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\",\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\",\"name\":\"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg\",\"datePublished\":\"2025-06-09T17:08:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg\",\"width\":760,\"height\":428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portaldoestado.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portaldoestado.com.br\/#website\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"name\":\"Portal do Estado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portaldoestado.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portaldoestado.com.br\/#organization\",\"name\":\"Portal do Estado\",\"url\":\"https:\/\/portaldoestado.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"contentUrl\":\"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png\",\"width\":1024,\"height\":350,\"caption\":\"Portal do Estado\"},\"image\":{\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/","og_locale":"pt_BR","og_type":"article","og_title":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado","og_description":"O secret\u00e1rio de sa\u00fade do Rio de Janeiro Daniel Soranz esteve presente e atestando a qualidade do grupo NefroCl\u00ednicas. NefroCl\u00ednicas com quase seis anos de exist\u00eancia, com sua funda\u00e7\u00e3o em Belo Horizonte \u2013 MG, inaugurou mais uma unidade no Rio de Janeiro no bairro da G\u00e1vea, nesta quinta-feira (05) no Centro M\u00e9dico do Shopping da \u2026","og_url":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/","og_site_name":"Portal do Estado","article_published_time":"2025-06-09T17:08:43+00:00","og_image":[{"width":760,"height":428,"url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","type":"image\/jpeg"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#article","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9"},"headline":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea","datePublished":"2025-06-09T17:08:43+00:00","mainEntityOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/"},"wordCount":325,"publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","keywords":["claudelopes70","nefroclinicas"],"articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/","url":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/","name":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea - Portal do Estado","isPartOf":{"@id":"https:\/\/portaldoestado.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage"},"image":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage"},"thumbnailUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","datePublished":"2025-06-09T17:08:43+00:00","breadcrumb":{"@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#primaryimage","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","width":760,"height":428},{"@type":"BreadcrumbList","@id":"https:\/\/portaldoestado.com.br\/index.php\/2025\/06\/09\/nefroclinicas-abre-nova-unidade-no-shopping-da-gavea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portaldoestado.com.br\/"},{"@type":"ListItem","position":2,"name":"NefroCl\u00ednicas abre nova unidade no Shopping da G\u00e1vea"}]},{"@type":"WebSite","@id":"https:\/\/portaldoestado.com.br\/#website","url":"https:\/\/portaldoestado.com.br\/","name":"Portal do Estado","description":"","publisher":{"@id":"https:\/\/portaldoestado.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portaldoestado.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portaldoestado.com.br\/#organization","name":"Portal do Estado","url":"https:\/\/portaldoestado.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","contentUrl":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/04\/cropped-6f69b19a-6472-43bf-b1b3-e1910bbbd4e8.png","width":1024,"height":350,"caption":"Portal do Estado"},"image":{"@id":"https:\/\/portaldoestado.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/5ca0174f3c8c84b59da62ea14b698cb9","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portaldoestado.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/portaldoestado.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"jetpack_featured_media_url":"https:\/\/portaldoestado.com.br\/wp-content\/uploads\/2025\/06\/nefroclinicas-shoppingdagavea-01-mavicaassessoria.jpg","_links":{"self":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=212"}],"version-history":[{"count":1,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/212\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/posts\/212\/revisions\/213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media\/211"}],"wp:attachment":[{"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaldoestado.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}